{"id":27937,"date":"2020-12-18T16:40:50","date_gmt":"2020-12-18T16:40:50","guid":{"rendered":"https:\/\/kdc1000.wpengine.com\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/"},"modified":"2022-10-14T05:00:41","modified_gmt":"2022-10-14T05:00:41","slug":"20-r04478-east-kansas-agri-energy-llc","status":"publish","type":"transparency_project","link":"https:\/\/www.kansascommerce.gov\/es\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/","title":{"rendered":"20-R04478 &#8211; East Kansas Agri Energy, LLC"},"template":"","class_list":["post-27937","transparency_project","type-transparency_project","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>20-R04478 - East Kansas Agri Energy, LLC - Kansas Department of Commerce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kansascommerce.gov\/es\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"20-R04478 - East Kansas Agri Energy, LLC - Kansas Department of Commerce\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kansascommerce.gov\/es\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/\" \/>\n<meta property=\"og:site_name\" content=\"Kansas Department of Commerce\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KansasCommerce\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-14T05:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kansascommerce.gov\/wp-content\/uploads\/2020\/09\/KDC_OG-MEta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@KansasCommerce\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kansascommerce.gov\\\/transparency_project\\\/20-r04478-east-kansas-agri-energy-llc\\\/\",\"url\":\"https:\\\/\\\/www.kansascommerce.gov\\\/transparency_project\\\/20-r04478-east-kansas-agri-energy-llc\\\/\",\"name\":\"20-R04478 - East Kansas Agri Energy, LLC - Kansas Department of Commerce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kansascommerce.gov\\\/#website\"},\"datePublished\":\"2020-12-18T16:40:50+00:00\",\"dateModified\":\"2022-10-14T05:00:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kansascommerce.gov\\\/transparency_project\\\/20-r04478-east-kansas-agri-energy-llc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kansascommerce.gov\\\/transparency_project\\\/20-r04478-east-kansas-agri-energy-llc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kansascommerce.gov\\\/transparency_project\\\/20-r04478-east-kansas-agri-energy-llc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kansascommerce.gov\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"20-R04478 &#8211; East Kansas Agri Energy, LLC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kansascommerce.gov\\\/#website\",\"url\":\"https:\\\/\\\/www.kansascommerce.gov\\\/\",\"name\":\"Kansas Department of Commerce\",\"description\":\"Empowering Prosperity\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kansascommerce.gov\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kansascommerce.gov\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kansascommerce.gov\\\/#organization\",\"name\":\"Kansas Department of Commerce\",\"url\":\"https:\\\/\\\/www.kansascommerce.gov\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.kansascommerce.gov\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kansascommerce.gov\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/kdc_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.kansascommerce.gov\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/kdc_logo.png\",\"width\":600,\"height\":347,\"caption\":\"Kansas Department of Commerce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kansascommerce.gov\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KansasCommerce\\\/\",\"https:\\\/\\\/x.com\\\/KansasCommerce\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kansas-department-of-commerce\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"20-R04478 - East Kansas Agri Energy, LLC - Kansas Department of Commerce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kansascommerce.gov\/es\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/","og_locale":"es_ES","og_type":"article","og_title":"20-R04478 - East Kansas Agri Energy, LLC - Kansas Department of Commerce","og_url":"https:\/\/www.kansascommerce.gov\/es\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/","og_site_name":"Kansas Department of Commerce","article_publisher":"https:\/\/www.facebook.com\/KansasCommerce\/","article_modified_time":"2022-10-14T05:00:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.kansascommerce.gov\/wp-content\/uploads\/2020\/09\/KDC_OG-MEta.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@KansasCommerce","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kansascommerce.gov\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/","url":"https:\/\/www.kansascommerce.gov\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/","name":"20-R04478 - East Kansas Agri Energy, LLC - Kansas Department of Commerce","isPartOf":{"@id":"https:\/\/www.kansascommerce.gov\/#website"},"datePublished":"2020-12-18T16:40:50+00:00","dateModified":"2022-10-14T05:00:41+00:00","breadcrumb":{"@id":"https:\/\/www.kansascommerce.gov\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kansascommerce.gov\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kansascommerce.gov\/transparency_project\/20-r04478-east-kansas-agri-energy-llc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kansascommerce.gov\/"},{"@type":"ListItem","position":2,"name":"20-R04478 &#8211; East Kansas Agri Energy, LLC"}]},{"@type":"WebSite","@id":"https:\/\/www.kansascommerce.gov\/#website","url":"https:\/\/www.kansascommerce.gov\/","name":"Departamento de Comercio de Kansas","description":"Fomentar la prosperidad","publisher":{"@id":"https:\/\/www.kansascommerce.gov\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kansascommerce.gov\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.kansascommerce.gov\/#organization","name":"Departamento de Comercio de Kansas","url":"https:\/\/www.kansascommerce.gov\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.kansascommerce.gov\/#\/schema\/logo\/image\/","url":"https:\/\/www.kansascommerce.gov\/wp-content\/uploads\/2020\/07\/kdc_logo.png","contentUrl":"https:\/\/www.kansascommerce.gov\/wp-content\/uploads\/2020\/07\/kdc_logo.png","width":600,"height":347,"caption":"Kansas Department of Commerce"},"image":{"@id":"https:\/\/www.kansascommerce.gov\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KansasCommerce\/","https:\/\/x.com\/KansasCommerce","https:\/\/www.linkedin.com\/company\/kansas-department-of-commerce\/"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:08:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.kansascommerce.gov\/es\/wp-json\/wp\/v2\/transparency_project\/27937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kansascommerce.gov\/es\/wp-json\/wp\/v2\/transparency_project"}],"about":[{"href":"https:\/\/www.kansascommerce.gov\/es\/wp-json\/wp\/v2\/types\/transparency_project"}],"wp:attachment":[{"href":"https:\/\/www.kansascommerce.gov\/es\/wp-json\/wp\/v2\/media?parent=27937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}